{"id":7364,"date":"2020-04-01T13:06:11","date_gmt":"2020-04-01T11:06:11","guid":{"rendered":"https:\/\/www.cortecarezzabella.com\/?post_type=product&#038;p=7364"},"modified":"2025-12-15T09:44:17","modified_gmt":"2025-12-15T08:44:17","slug":"confezione-regalo-box-cartone-avana","status":"publish","type":"product","link":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/","title":{"rendered":"Confezione regalo &#8211; Box cartone avana"},"content":{"rendered":"<p><strong>I regali gastronomici <\/strong>sono sempre tra i pi\u00f9 apprezzati e il motivo \u00e8 che uniscono cura e coccola<\/p>\n<p>Vuoi regalare i nostri prodotti ma li vuoi far recapitare confezionati?<\/p>\n<p>Ti proponiamo 2 taglie di box&nbsp; in carta color avana, perch\u00e8 crediamo valorizzino ancora di pi\u00f9 i nostri prodotto creati &nbsp;con amore.<\/p>\n<p>Aggiungila al carrello se vuoi che il tuo ordine arrivi confezionato e specifica nelle note se vuoi allegare un pensiero, lo faremo con gioia noi per te!<\/p>\n<p>Ci teniamo a sottolineare che le nostre box sono a Km0, sono nate infatti da una collaborazione con aziende del territorio.<\/p>\n<p>Confezioniamo le box con cura perch\u00e8 possano strappare un sorriso a chi le ricever\u00e0!<\/p>\n<p>Le rendiamo belle con nastri e tag ed elementi naturali che arrivano dalla campagna e assicuriamo i prodotti con paglietta e le inseriamo all&#8217;interno di una scatola pi\u00f9 grande pronte per essere inviate.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Box in carta avana con grafica esclusiva Corte Carezzabella disponibile in 2 misure&nbsp;<\/p>\n","protected":false},"featured_media":9735,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":["post-7364","product","type-product","status-publish","has-post-thumbnail","product_cat-regalistica-2","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Confezione regalo - Box cartone avana &#187; Corte Carezzabella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Confezione regalo - Box cartone avana &#187; Corte Carezzabella\" \/>\n<meta property=\"og:description\" content=\"Box in carta avana con grafica esclusiva Corte Carezzabella disponibile in 2 misure&nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/\" \/>\n<meta property=\"og:site_name\" content=\"Corte Carezzabella\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T08:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/04\/750_2685-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/\",\"name\":\"Confezione regalo - Box cartone avana &#187; Corte Carezzabella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/750_2685-scaled.jpg\",\"datePublished\":\"2020-04-01T11:06:11+00:00\",\"dateModified\":\"2025-12-15T08:44:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/750_2685-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/750_2685-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop\\\/confezione-regalo-box-cartone-avana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop online\",\"item\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/shop-online\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Regalistica\",\"item\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/categoria\\\/regalistica-2\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Confezione regalo &#8211; Box cartone avana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/\",\"name\":\"Corte Carezzabella\",\"description\":\"Agriturismo Corte Carezzabella\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#organization\",\"name\":\"IL FRUTTETO DI SAN MARTINO S.S.\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_laBottega-posta-elttr-piccola.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_laBottega-posta-elttr-piccola.jpg\",\"width\":160,\"height\":115,\"caption\":\"IL FRUTTETO DI SAN MARTINO S.S.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Confezione regalo - Box cartone avana &#187; Corte Carezzabella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/","og_locale":"nl_NL","og_type":"article","og_title":"Confezione regalo - Box cartone avana &#187; Corte Carezzabella","og_description":"Box in carta avana con grafica esclusiva Corte Carezzabella disponibile in 2 misure&nbsp;","og_url":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/","og_site_name":"Corte Carezzabella","article_modified_time":"2025-12-15T08:44:17+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/04\/750_2685-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/","url":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/","name":"Confezione regalo - Box cartone avana &#187; Corte Carezzabella","isPartOf":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/#primaryimage"},"image":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/04\/750_2685-scaled.jpg","datePublished":"2020-04-01T11:06:11+00:00","dateModified":"2025-12-15T08:44:17+00:00","breadcrumb":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/#primaryimage","url":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/04\/750_2685-scaled.jpg","contentUrl":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/04\/750_2685-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/www.cortecarezzabella.com\/nl\/shop\/confezione-regalo-box-cartone-avana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cortecarezzabella.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Shop online","item":"https:\/\/www.cortecarezzabella.com\/nl\/shop-online\/"},{"@type":"ListItem","position":3,"name":"Regalistica","item":"https:\/\/www.cortecarezzabella.com\/nl\/categoria\/regalistica-2\/"},{"@type":"ListItem","position":4,"name":"Confezione regalo &#8211; Box cartone avana"}]},{"@type":"WebSite","@id":"https:\/\/www.cortecarezzabella.com\/nl\/#website","url":"https:\/\/www.cortecarezzabella.com\/nl\/","name":"Corte Carezzabella","description":"Agriturismo Corte Carezzabella","publisher":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cortecarezzabella.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.cortecarezzabella.com\/nl\/#organization","name":"IL FRUTTETO DI SAN MARTINO S.S.","url":"https:\/\/www.cortecarezzabella.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.cortecarezzabella.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/03\/LOGO_laBottega-posta-elttr-piccola.jpg","contentUrl":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/03\/LOGO_laBottega-posta-elttr-piccola.jpg","width":160,"height":115,"caption":"IL FRUTTETO DI SAN MARTINO S.S."},"image":{"@id":"https:\/\/www.cortecarezzabella.com\/nl\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/product\/7364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/comments?post=7364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/media\/9735"}],"wp:attachment":[{"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/media?parent=7364"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/product_brand?post=7364"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/product_cat?post=7364"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.cortecarezzabella.com\/nl\/wp-json\/wp\/v2\/product_tag?post=7364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}