{"id":173,"count":2,"description":"Gli \"sfarinati\" non sono altro che sottoprodotti della macinazione del nostro grano. \r\nA seconda del tipo di molitura si possono ottenere diversi sfarinati: con la prima molitura viene eliminata la crusca, con la seconda il tritello e con la terza il farinaccio ( considerato il pi\u00f9 nobile tra i sottoprodotti).\r\nTutti e tre sono costituiti in prevalenza da fibre e sono ricchi di principi nutritivi. Per questo renderanno ancora pi\u00f9 rustici e gustosi gli impasti per realizzare pane, pasta e dolci ma possono prestarsi anche a preparazioni alternative in cucina.\r\nFai il pieno di salute e porta in cucina i derivati del nostro grano.\r\n","link":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/","name":"Sfarinati","slug":"sfarinati","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":9,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sfarinati Archivi &#187; Corte Carezzabella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sfarinati Archivi &#187; Corte Carezzabella\" \/>\n<meta property=\"og:description\" content=\"Gli &#8220;sfarinati&#8221; non sono altro che sottoprodotti della macinazione del nostro grano. A seconda del tipo di molitura si possono ottenere diversi sfarinati: con la prima molitura viene eliminata la crusca, con la seconda il tritello e con la terza il farinaccio ( considerato il pi\u00f9 nobile tra i sottoprodotti). Tutti e tre sono costituiti in prevalenza da fibre e sono ricchi di principi nutritivi. Per questo renderanno ancora pi\u00f9 rustici e gustosi gli impasti per realizzare pane, pasta e dolci ma possono prestarsi anche a preparazioni alternative in cucina. Fai il pieno di salute e porta in cucina i derivati del nostro grano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/\" \/>\n<meta property=\"og:site_name\" content=\"Corte Carezzabella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/categoria\\\/sfarinati\\\/\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/categoria\\\/sfarinati\\\/\",\"name\":\"Sfarinati Archivi &#187; Corte Carezzabella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/categoria\\\/sfarinati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/categoria\\\/sfarinati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sfarinati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/\",\"name\":\"Corte Carezzabella\",\"description\":\"Agriturismo Corte Carezzabella\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#organization\",\"name\":\"IL FRUTTETO DI SAN MARTINO S.S.\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_laBottega-posta-elttr-piccola.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/LOGO_laBottega-posta-elttr-piccola.jpg\",\"width\":160,\"height\":115,\"caption\":\"IL FRUTTETO DI SAN MARTINO S.S.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cortecarezzabella.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sfarinati Archivi &#187; Corte Carezzabella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/","og_locale":"it_IT","og_type":"article","og_title":"Sfarinati Archivi &#187; Corte Carezzabella","og_description":"Gli &#8220;sfarinati&#8221; non sono altro che sottoprodotti della macinazione del nostro grano. A seconda del tipo di molitura si possono ottenere diversi sfarinati: con la prima molitura viene eliminata la crusca, con la seconda il tritello e con la terza il farinaccio ( considerato il pi\u00f9 nobile tra i sottoprodotti). Tutti e tre sono costituiti in prevalenza da fibre e sono ricchi di principi nutritivi. Per questo renderanno ancora pi\u00f9 rustici e gustosi gli impasti per realizzare pane, pasta e dolci ma possono prestarsi anche a preparazioni alternative in cucina. Fai il pieno di salute e porta in cucina i derivati del nostro grano.","og_url":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/","og_site_name":"Corte Carezzabella","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/","url":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/","name":"Sfarinati Archivi &#187; Corte Carezzabella","isPartOf":{"@id":"https:\/\/www.cortecarezzabella.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cortecarezzabella.com\/it\/categoria\/sfarinati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cortecarezzabella.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sfarinati"}]},{"@type":"WebSite","@id":"https:\/\/www.cortecarezzabella.com\/it\/#website","url":"https:\/\/www.cortecarezzabella.com\/it\/","name":"Corte Carezzabella","description":"Agriturismo Corte Carezzabella","publisher":{"@id":"https:\/\/www.cortecarezzabella.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cortecarezzabella.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.cortecarezzabella.com\/it\/#organization","name":"IL FRUTTETO DI SAN MARTINO S.S.","url":"https:\/\/www.cortecarezzabella.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.cortecarezzabella.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/03\/LOGO_laBottega-posta-elttr-piccola.jpg","contentUrl":"https:\/\/www.cortecarezzabella.com\/wp-content\/uploads\/2020\/03\/LOGO_laBottega-posta-elttr-piccola.jpg","width":160,"height":115,"caption":"IL FRUTTETO DI SAN MARTINO S.S."},"image":{"@id":"https:\/\/www.cortecarezzabella.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.cortecarezzabella.com\/it\/wp-json\/wp\/v2\/product_cat\/173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cortecarezzabella.com\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.cortecarezzabella.com\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.cortecarezzabella.com\/it\/wp-json\/wp\/v2\/product?product_cat=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}